{"id":254,"date":"2014-03-20T16:02:00","date_gmt":"2014-03-20T15:02:00","guid":{"rendered":"https:\/\/citycamps.com\/campers-2\/"},"modified":"2014-03-24T20:41:30","modified_gmt":"2014-03-24T19:41:30","slug":"camping-cars","status":"publish","type":"page","link":"https:\/\/citycamps.com\/fr\/camping-cars\/","title":{"rendered":"Les Citycamps accueillent chaleureusement les camping-cars"},"content":{"rendered":"<p>Voyager en camping-car est tr\u00e8s en vogue. De plus en plus de voyageurs n\u00e9erlandais ou \u00e9trangers choisissent les Pays-Bas pour y passer un s\u00e9jour, plus ou moins long, en camping-car. Et s\u2019arr\u00eatent de plus en plus souvent dans un des citycamps. Logique, car avec cette combinaison de moyen de locomotion et de s\u00e9jour il est tr\u00e8s agr\u00e9able de faire un parcours pour visiter les diff\u00e9rente villes.<\/p>\n<p>Les campeurs en camping-car sont les bienvenues dans les Citycamps. Tous nos campings offrent des nombreuses possibilit\u00e9s pour y passer la nuit dans votre camping-car. Sur un de nos emplacements pour camping-cars ou un des emplacements r\u00e9guliers du camping. Dans tous les cas nous proposons de bons \u00e9quipements pour les camping-cars:<\/p>\n<ul>\n<li>des emplacements en dur ou des emplacements disposant d\u2019un sol porteur;<\/li>\n<li>des emplacements faciles d\u2019acc\u00e8s proches d\u2019un chemin d\u2019acc\u00e8s en dur ou bien praticable;<\/li>\n<li>des \u00e9quipements pour vous permettre d\u2019\u00e9vacuer vos eaux us\u00e9es et pour remplir votre r\u00e9serve d\u2019eau;<\/li>\n<li>des \u00e9quipements pour vidanger vos toilettes chimiques.<\/li>\n<\/ul>\n<p>De nombreux Citycamps ont pr\u00e9vu des emplacements sp\u00e9ciaux pour camping-cars devant le portail du camping.<\/p>\n<p>De plus vous pourrez bien entendu profiter de tous les autres facilit\u00e9s pr\u00e9sentes sur les campings, comme les connexions d\u2019\u00e9lectricit\u00e9 et d\u2019eau, les sanitaires, la piscine, le restaurant et les \u00e9quipements sportifs et ludiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voyager en camping-car est tr\u00e8s en vogue. De plus en plus de voyageurs n\u00e9erlandais ou \u00e9trangers choisissent les Pays-Bas pour y passer un s\u00e9jour, plus ou moins long, en camping-car. Et s\u2019arr\u00eatent de plus en plus souvent dans un des citycamps. Logique,<\/p>\n<div class=\"read-more-icon\">&#x27b2;<\/div>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-254","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Citycamps accueillent chaleureusement les camping-cars - City Camps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/citycamps.com\/campervriendelijk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Citycamps accueillent chaleureusement les camping-cars - City Camps\" \/>\n<meta property=\"og:description\" content=\"Voyager en camping-car est tr\u00e8s en vogue. De plus en plus de voyageurs n\u00e9erlandais ou \u00e9trangers choisissent les Pays-Bas pour y passer un s\u00e9jour, plus ou moins long, en camping-car. Et s\u2019arr\u00eatent de plus en plus souvent dans un des citycamps. Logique,&#x27b2;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/citycamps.com\/campervriendelijk\/\" \/>\n<meta property=\"og:site_name\" content=\"City Camps\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-24T19:41:30+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/citycamps.com\\\/campervriendelijk\\\/\",\"url\":\"https:\\\/\\\/citycamps.com\\\/campervriendelijk\\\/\",\"name\":\"Les Citycamps accueillent chaleureusement les camping-cars - City Camps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/citycamps.com\\\/fr\\\/#website\"},\"datePublished\":\"2014-03-20T15:02:00+00:00\",\"dateModified\":\"2014-03-24T19:41:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/citycamps.com\\\/campervriendelijk\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/citycamps.com\\\/campervriendelijk\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/citycamps.com\\\/campervriendelijk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/citycamps.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Citycamps accueillent chaleureusement les camping-cars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/citycamps.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/citycamps.com\\\/fr\\\/\",\"name\":\"City Camps\",\"description\":\"Kamperen met de stad binnen handbereik!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/citycamps.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Citycamps accueillent chaleureusement les camping-cars - City Camps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/citycamps.com\/campervriendelijk\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Citycamps accueillent chaleureusement les camping-cars - City Camps","og_description":"Voyager en camping-car est tr\u00e8s en vogue. De plus en plus de voyageurs n\u00e9erlandais ou \u00e9trangers choisissent les Pays-Bas pour y passer un s\u00e9jour, plus ou moins long, en camping-car. Et s\u2019arr\u00eatent de plus en plus souvent dans un des citycamps. Logique,&#x27b2;","og_url":"https:\/\/citycamps.com\/campervriendelijk\/","og_site_name":"City Camps","article_modified_time":"2014-03-24T19:41:30+00:00","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/citycamps.com\/campervriendelijk\/","url":"https:\/\/citycamps.com\/campervriendelijk\/","name":"Les Citycamps accueillent chaleureusement les camping-cars - City Camps","isPartOf":{"@id":"https:\/\/citycamps.com\/fr\/#website"},"datePublished":"2014-03-20T15:02:00+00:00","dateModified":"2014-03-24T19:41:30+00:00","breadcrumb":{"@id":"https:\/\/citycamps.com\/campervriendelijk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/citycamps.com\/campervriendelijk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/citycamps.com\/campervriendelijk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/citycamps.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Citycamps accueillent chaleureusement les camping-cars"}]},{"@type":"WebSite","@id":"https:\/\/citycamps.com\/fr\/#website","url":"https:\/\/citycamps.com\/fr\/","name":"City Camps","description":"Kamperen met de stad binnen handbereik!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/citycamps.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/pages\/254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/comments?post=254"}],"version-history":[{"count":3,"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/pages\/254\/revisions"}],"predecessor-version":[{"id":279,"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/pages\/254\/revisions\/279"}],"wp:attachment":[{"href":"https:\/\/citycamps.com\/fr\/wp-json\/wp\/v2\/media?parent=254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}